{"id":1611,"date":"2022-04-25T14:38:48","date_gmt":"2022-04-25T17:38:48","guid":{"rendered":"https:\/\/www.grefortec.com.br\/?p=1611"},"modified":"2022-10-11T05:13:06","modified_gmt":"2022-10-11T05:13:06","slug":"desgaste-por-abrasao-quais-as-causas-e-como-prevenir","status":"publish","type":"post","link":"https:\/\/site2022.grefortec.com.br\/index.php\/desgaste-por-abrasao-quais-as-causas-e-como-prevenir\/","title":{"rendered":"Desgaste por abras\u00e3o: quais as causas e como prevenir?"},"content":{"rendered":"<div class=\"vgblk-rw-wrapper limit-wrapper\">\n<p>O desgaste por abras\u00e3o \u00e9 um dos mais comuns em equipamentos e m\u00e1quinas industriais. Ele \u00e9 caracterizado pela remo\u00e7\u00e3o de material na superf\u00edcie das pe\u00e7as, principalmente quando ocorre atrito entre elas durante o movimento (abras\u00e3o por 2 corpos). Ou tamb\u00e9m, quando h\u00e1 um terceiro corpo (areia, por exemplo) entre as pe\u00e7as.<\/p>\n\n\n\n<p>Em colheitadeiras de arroz, por exemplo, o desgaste por abras\u00e3o \u00e9 causado pela casca do pr\u00f3prio arroz, que cont\u00e9m grande quantidade de s\u00edlica em sua superf\u00edcie. J\u00e1 em tratores, o desgaste est\u00e1 intimamente ligado \u00e0 eleva\u00e7\u00e3o da temperatura gerada pelo atrito entre seus componentes. Outros exemplos s\u00e3o o desgaste nas veda\u00e7\u00f5es de eixos, mancais e engrenagens.<\/p>\n\n\n\n<p>Alguns cuidados b\u00e1sicos podem fazer toda a diferen\u00e7a na preven\u00e7\u00e3o desse problema. Como por exemplo: seguir as recomenda\u00e7\u00f5es do fabricante, armazenar o equipamento em local adequado e saber selecionar o material correto para cada pe\u00e7a (nem sempre os de maior dureza s\u00e3o os mais indicados para evitar o desgaste por abras\u00e3o). Al\u00e9m disso, \u00e9 importante realizar o tratamento das pe\u00e7as, incluindo o tratamento t\u00e9rmico e <a href=\"https:\/\/rijeza.com.br\/blog\/revestimentos-contra-desgastes-como-especificar\/\" target=\"_blank\" rel=\"noreferrer noopener\">aplica\u00e7\u00e3o de revestimento contra desgastes<\/a>.&nbsp;<\/p>\n\n\n\n<p>A Grefortec, realiza o tratamento de pe\u00e7as para diversos setores da ind\u00fastria. Somos especialistas em prevenir o desgaste por abras\u00e3o e trabalhamos com grandes demandas. Contamos com o apoio de equipes t\u00e9cnicas especializadas e laborat\u00f3rio pr\u00f3prio para a realiza\u00e7\u00e3o de testes e comprova\u00e7\u00e3o de qualidade!<\/p>\n\n\n\n<p>Para saber mais sobre o desgaste por abras\u00e3o e como preveni-lo, <strong>fa\u00e7a o download do material explicativo abaixo<\/strong>.<\/p>\n\n\n\n<p><strong>Tenha acesso agora mesmo ao ebook!<\/strong><\/p>\n\n\n\n<p><strong>Para receber esse material totalmente gratuito, precisamos somente de algumas informa\u00e7\u00f5es!<\/strong><\/p>\n\n\n\n<p class=\"has-col-ffffff-color has-text-color\">.<\/p>\n\n\n<p>[contact-form-7 id=&#8221;1610&#8243; title=&#8221;Desgaste por abrasao&#8221;]<\/p>\n<\/div><!-- .vgblk-rw-wrapper -->","protected":false},"excerpt":{"rendered":"<p>O desgaste por abras\u00e3o \u00e9 um dos mais comuns em equipamentos e m\u00e1quinas industriais. Ele \u00e9 caracterizado pela remo\u00e7\u00e3o de material na superf\u00edcie das pe\u00e7as, principalmente quando ocorre atrito entre elas durante o movimento (abras\u00e3o por 2 corpos). Ou tamb\u00e9m, quando h\u00e1 um terceiro corpo (areia, por exemplo) entre as pe\u00e7as. Em colheitadeiras de arroz,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":987796,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"jetpack_featured_media_url":"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/04\/8.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1611"}],"version-history":[{"count":1,"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1611\/revisions"}],"predecessor-version":[{"id":987797,"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1611\/revisions\/987797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/media\/987796"}],"wp:attachment":[{"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}