{"id":988349,"date":"2022-11-16T04:20:24","date_gmt":"2022-11-16T04:20:24","guid":{"rendered":"https:\/\/site2022.grefortec.com.br\/?page_id=988349"},"modified":"2023-01-05T01:30:08","modified_gmt":"2023-01-05T01:30:08","slug":"envelhecimento","status":"publish","type":"page","link":"https:\/\/site2022.grefortec.com.br\/index.php\/tratamento-termico\/envelhecimento\/","title":{"rendered":"Envelhecimento"},"content":{"rendered":"<div class=\"vgblk-rw-wrapper limit-wrapper\">\n<h2>\n\tEnvelhecimento\n\t<\/h2>\n\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/11\/envelhecimento.jpg\" alt=\"Envelhecimento\" itemprop=\"image\" height=\"600\" width=\"800\" title=\"envelhecimento\" onerror=\"this.style.display='none'\"  sizes=\"auto, (max-width: 768px) 100vw, 100vw\" srcset=\"data:image\/svg+xml;utf8,&lt;svg%20xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;%20viewBox=&quot;0%200%20800%20600&quot;%20height=&quot;600px&quot;%20width=&quot;800px&quot;\/&gt;\" data-srcset=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/11\/envelhecimento.jpg 800w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/11\/envelhecimento-300x225.jpg 300w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/11\/envelhecimento-768x576.jpg 768w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/11\/envelhecimento-630x473.jpg 630w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/11\/envelhecimento-420x315.jpg 420w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/11\/envelhecimento-315x236.jpg 315w\" \/>\t\t\t\t\t\t\t\n\t<p>Processo de tratamento t\u00e9rmico usado para aumentar a dureza e as propriedades mec\u00e2nicas de materiais sob condi\u00e7\u00f5es controladas de aquecimento e resfriamento.<\/p>\n<p>O aumento da dureza \u00e9 proporcionado pelos precipitados que se formam durante o processo de tratamento t\u00e9rmico.<\/p>\n<p><strong>A Grefortec tamb\u00e9m fabrica e realiza a manuten\u00e7\u00e3o em fornos para o Tratamento T\u00e9rmico de Envelhecimento, para saber mais, <a href=\"https:\/\/site2022.grefortec.com.br\/?page_id=987682\"><u>clique aqui<\/u><\/a>.<\/strong><\/p>\n<h2>\n\tBenef\u00edcios da Manuten\u00e7\u00e3o <br \/><strong>Grefortec<\/strong>\n\t<\/h2>\n\t<p>Contamos com uma equipe qualificada para atender manuten\u00e7\u00f5es corretivas e preventivas em equipamento industriais da nossa marca e tamb\u00e9m de outros fabricantes. Nossos profissionais s\u00e3o treinados e habilitados de acordo com as Normas de Seguran\u00e7a. Vamos at\u00e9 sua empresa para realizar a manuten\u00e7\u00e3o in loco.<\/p>\n\t\t\t\t\t\t\t65%\t\t\t\t\n\t\t\t<style>\n\t\t\t\t.fl-node- .fl-number-bars-container {\n\t\t\t\t\tbackground-color: var( --vamtam-accent-color-7 );\n\t\t\t\t}\n\t\t\t\t.fl-node- .fl-number-bar {\n\t\t\t\t\tbackground-color: var( --vamtam-accent-color-1 );\n\t\t\t\t}\n\t\t\t<\/style>\n\t<p>Do tempo de produ\u00e7\u00e3o \u00e9 desperdi\u00e7ado pela falta de manuten\u00e7\u00e3o <\/p>\n\t\t\t\t\t\t\t88%\t\t\t\t\n\t\t\t<style>\n\t\t\t\t.fl-node- .fl-number-bars-container {\n\t\t\t\t\tbackground-color: var( --vamtam-accent-color-7 );\n\t\t\t\t}\n\t\t\t\t.fl-node- .fl-number-bar {\n\t\t\t\t\tbackground-color: var( --vamtam-accent-color-1 );\n\t\t\t\t}\n\t\t\t<\/style>\n\t<p>Das empresas industriais utilizam a manuten\u00e7\u00e3o preventiva<\/p>\n\t\t\t\t\t\t\t97%\t\t\t\t\n\t\t\t<style>\n\t\t\t\t.fl-node- .fl-number-bars-container {\n\t\t\t\t\tbackground-color: var( --vamtam-accent-color-7 );\n\t\t\t\t}\n\t\t\t\t.fl-node- .fl-number-bar {\n\t\t\t\t\tbackground-color: var( --vamtam-accent-color-1 );\n\t\t\t\t}\n\t\t\t<\/style>\n\t<p>\u00c9 o \u00edndice de satisfa\u00e7\u00e3o com a manuten\u00e7\u00e3o Grefortec<\/p>\n<h3>\n\tReformas e Retrofit\n\t<\/h3>\n\t<p>Equipe especializada em reformas gerais, recuperando desde a estrutura e chaparia at\u00e9 as partes eletroeletr\u00f4nicas. A Grefortec tamb\u00e9m possui Know-Wow para servi\u00e7os de retrofit, reformas refrat\u00e1rias e de isola\u00e7\u00e3o.<\/p>\n<h3>\n\tDisponibilidade 24h\n\t<\/h3>\n\t<p>Nossa equipe t\u00e9cnica est\u00e1 dispon\u00edvel 24h por dia, com a possibilidade de realizar a manuten\u00e7\u00e3o in loco, sem necessidade de deslocamento. N\u00f3s vamos at\u00e9 a sua empresa!<\/p>\n\t<h2><strong>Pe\u00e7as de Reposi\u00e7\u00e3o<\/strong><\/h2>\n<p>Resist\u00eancias, tubos radiantes, correntes transportadoras, recirculadores de atmosfera, cestos, grelhas e itens diversos:<\/p>\n\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/resistencias-630x420.jpeg\" alt=\"Resist\u00eancia\" itemprop=\"image\" height=\"420\" width=\"630\" title=\"resistencias\" onerror=\"this.style.display='none'\"  sizes=\"auto, (max-width: 768px) 100vw, 100vw\" srcset=\"data:image\/svg+xml;utf8,&lt;svg%20xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;%20viewBox=&quot;0%200%20900%20600&quot;%20height=&quot;600px&quot;%20width=&quot;900px&quot;\/&gt;\" data-srcset=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/resistencias-630x420.jpeg 630w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/resistencias-300x200.jpeg 300w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/resistencias-768x512.jpeg 768w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/resistencias-420x280.jpeg 420w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/resistencias-840x560.jpeg 840w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/resistencias-315x210.jpeg 315w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/resistencias.jpeg 900w\" \/>\t\t\t\t\t\t\t\n\t<h4>Resist\u00eancia<\/h4>\n\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/tubos-radiantes-630x420.jpeg\" alt=\"tubos-radiantes\" itemprop=\"image\" height=\"420\" width=\"630\" title=\"tubos-radiantes\" onerror=\"this.style.display='none'\"  sizes=\"auto, (max-width: 768px) 100vw, 100vw\" srcset=\"data:image\/svg+xml;utf8,&lt;svg%20xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;%20viewBox=&quot;0%200%20900%20600&quot;%20height=&quot;600px&quot;%20width=&quot;900px&quot;\/&gt;\" data-srcset=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/tubos-radiantes-630x420.jpeg 630w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/tubos-radiantes-300x200.jpeg 300w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/tubos-radiantes-768x512.jpeg 768w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/tubos-radiantes-420x280.jpeg 420w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/tubos-radiantes-840x560.jpeg 840w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/tubos-radiantes-315x210.jpeg 315w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/tubos-radiantes.jpeg 900w\" \/>\t\t\t\t\t\t\t\n\t<h4>Tubos Radiadores<\/h4>\n\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/correntes-transportadoras-630x420.jpeg\" alt=\"correntes-transportadoras\" itemprop=\"image\" height=\"420\" width=\"630\" title=\"correntes-transportadoras\" onerror=\"this.style.display='none'\"  sizes=\"auto, (max-width: 768px) 100vw, 100vw\" srcset=\"data:image\/svg+xml;utf8,&lt;svg%20xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;%20viewBox=&quot;0%200%20900%20600&quot;%20height=&quot;600px&quot;%20width=&quot;900px&quot;\/&gt;\" data-srcset=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/correntes-transportadoras-630x420.jpeg 630w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/correntes-transportadoras-300x200.jpeg 300w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/correntes-transportadoras-768x512.jpeg 768w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/correntes-transportadoras-420x280.jpeg 420w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/correntes-transportadoras-840x560.jpeg 840w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/correntes-transportadoras-315x210.jpeg 315w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/correntes-transportadoras.jpeg 900w\" \/>\t\t\t\t\t\t\t\n\t<h4>Correntes Transportadoras<\/h4>\n\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/recirculadores.jpeg\" alt=\"recirculadores\" itemprop=\"image\" height=\"600\" width=\"900\" title=\"recirculadores\" onerror=\"this.style.display='none'\"  sizes=\"auto, (max-width: 768px) 100vw, 100vw\" srcset=\"data:image\/svg+xml;utf8,&lt;svg%20xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;%20viewBox=&quot;0%200%20900%20600&quot;%20height=&quot;600px&quot;%20width=&quot;900px&quot;\/&gt;\" data-srcset=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/recirculadores.jpeg 900w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/recirculadores-300x200.jpeg 300w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/recirculadores-768x512.jpeg 768w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/recirculadores-630x420.jpeg 630w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/recirculadores-420x280.jpeg 420w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/recirculadores-840x560.jpeg 840w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/recirculadores-315x210.jpeg 315w\" \/>\t\t\t\t\t\t\t\n\t<h4>Circuladores de Atmosfera<\/h4>\n\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/cestos-grelhas-300x200-1.jpeg\" alt=\"cestos-grelhas-300x200\" itemprop=\"image\" height=\"200\" width=\"300\" title=\"cestos-grelhas-300x200\" onerror=\"this.style.display='none'\"  sizes=\"auto, (max-width: 768px) 100vw, 100vw\"\/>\t\t\t\t\t\t\t\n\t<h4>Cestos e Grelhas<\/h4>\n\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/itens-diversos.jpeg\" alt=\"itens-diversos\" itemprop=\"image\" height=\"600\" width=\"900\" title=\"itens-diversos\" onerror=\"this.style.display='none'\"  sizes=\"auto, (max-width: 768px) 100vw, 100vw\" srcset=\"data:image\/svg+xml;utf8,&lt;svg%20xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;%20viewBox=&quot;0%200%20900%20600&quot;%20height=&quot;600px&quot;%20width=&quot;900px&quot;\/&gt;\" data-srcset=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/itens-diversos.jpeg 900w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/itens-diversos-300x200.jpeg 300w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/itens-diversos-768x512.jpeg 768w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/itens-diversos-630x420.jpeg 630w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/itens-diversos-420x280.jpeg 420w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/itens-diversos-840x560.jpeg 840w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/itens-diversos-315x210.jpeg 315w\" \/>\t\t\t\t\t\t\t\n\t<h4>Itens Diversos<\/h4>\n\t<h2><strong>Solicitar Or\u00e7amento<\/strong><\/h2>\n    Aviso: O JavaScript \u00e9 necess\u00e1rio para esse conte\u00fado.\n        <!-- TODO: Move to Template File. -->\n        \n<\/div><!-- .vgblk-rw-wrapper -->","protected":false},"excerpt":{"rendered":"<p>Envelhecimento Processo de tratamento t\u00e9rmico usado para aumentar a dureza e as propriedades mec\u00e2nicas de materiais sob condi\u00e7\u00f5es controladas de aquecimento e resfriamento. O aumento da dureza \u00e9 proporcionado pelos precipitados que se formam durante o processo de tratamento t\u00e9rmico. A Grefortec tamb\u00e9m fabrica e realiza a manuten\u00e7\u00e3o em fornos para o Tratamento T\u00e9rmico de&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":12320,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-988349","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/pages\/988349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=988349"}],"version-history":[{"count":5,"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/pages\/988349\/revisions"}],"predecessor-version":[{"id":988544,"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/pages\/988349\/revisions\/988544"}],"up":[{"embeddable":true,"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/pages\/12320"}],"wp:attachment":[{"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=988349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}