{"id":987853,"date":"2022-10-11T17:10:29","date_gmt":"2022-10-11T17:10:29","guid":{"rendered":"https:\/\/site2022.grefortec.com.br\/?page_id=987853"},"modified":"2023-01-06T01:39:02","modified_gmt":"2023-01-06T01:39:02","slug":"estufas-estacionarias","status":"publish","type":"page","link":"https:\/\/site2022.grefortec.com.br\/index.php\/equipamentos-industriais\/estufas\/estufas-estacionarias\/","title":{"rendered":"Estufas Estacion\u00e1rias"},"content":{"rendered":"<div class=\"vgblk-rw-wrapper limit-wrapper\">\n<h2>\n\tEstufas Estacion\u00e1rias\n\t<\/h2>\n\t\n\t\t \t<div class=\"item\">            \n\t      <div class=\"clearfix\" style=\"max-width:Arraypx;\">\n\n\t        <ul id=\"gwts-gwl-img-gallery987976\" class=\"gwts-gwl-slidergal list-unstyled cS-hidden\" data-litebx=\"false\">\n\t\t\t\t    \n\t\t\t\t\t \t\t<li data-thumb=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/IMG_20160708_132405007-1030x579-1-150x150.jpeg\" data-responsive=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/IMG_20160708_132405007-1030x579-1-150x150.jpeg\" data-src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/IMG_20160708_132405007-1030x579-1.jpeg\" class=\"\"> \n              \t<img decoding=\"async\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/IMG_20160708_132405007-1030x579-1.jpeg\" alt=\"\"\/>\n              \t\t              <\/li>\n\t\t\t\t\t \t\n\t\t\t\t\t \t\t<li data-thumb=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/IMG_20160707_135455427-579x1030-1-150x150.jpeg\" data-responsive=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/IMG_20160707_135455427-579x1030-1-150x150.jpeg\" data-src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/IMG_20160707_135455427-579x1030-1.jpeg\" class=\"\"> \n              \t<img decoding=\"async\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/IMG_20160707_135455427-579x1030-1.jpeg\" alt=\"\"\/>\n              \t\t              <\/li>\n\t\t\t\t\t \t\n\t\t\t\t\t \t\t<li data-thumb=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/estufa-tipo-carro-1030x746-1-150x150.jpeg\" data-responsive=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/estufa-tipo-carro-1030x746-1-150x150.jpeg\" data-src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/estufa-tipo-carro-1030x746-1.jpeg\" class=\"\"> \n              \t<img decoding=\"async\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/estufa-tipo-carro-1030x746-1.jpeg\" alt=\"\"\/>\n              \t\t              <\/li>\n\t\t\t\t\t \t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<style type=\"text\/css\">\n\t\t\t\t.lSSlideOuter .lSSlideWrapper ul li img{\n\t\t\t\t  width: 100%;\n\t\t\t\t}\n\t\t\t<\/style>\n\n\t\t\t\t\t\t\t<script>\n\t\t\t\t\tjQuery(document).ready(function() {\n            var count  = 0\n              if (count === 1) return;\n              jQuery('#gwts-gwl-img-gallery987976').addClass('cS-hidden');\n                jQuery('#gwts-gwl-img-gallery987976').lightSlider({\n                  gallery:true,\t                        \n                  speed:500,\n                  auto:false,\n                  item: 1,\n\t\t\t\t\t\t\t    loop: false,\n\t\t\t\t\t\t\t    thumbItem: 6,\n\t\t\t\t\t\t\t    vertical: true,\n\t\t\t\t\t\t\t    verticalHeight:450,\n\t\t\t\t\t\t\t    vThumbWidth:100,\n\t\t\t\t\t\t\t    thumbMargin:4,\n\t\t\t\t\t\t\t    controls:false,\/\/navigation\n\t\t\t\t\t\t\t    responsive : [\n\t\t\t            {\n\t\t                breakpoint:800,\n\t\t                settings: {\n\t                    item:1,\n\t                    slideMove:1,\n\t                    verticalHeight:370,\n\t                    thumbItem:6,\n\t                  }\n\t\t\t            },\n\t\t\t            {\n\t\t                breakpoint:641,\n\t\t                settings: {\n\t                    item:1,\n\t                    slideMove:1,\n\t                    verticalHeight:300,\n\t                    thumbItem:6,\n\t                  }\n\t\t\t            },\n\t\t\t            {\n\t\t                breakpoint:480,\n\t\t                settings: {\n\t                    item:1,\n\t                    slideMove:1,\n\t                    verticalHeight:200,\n\t                    thumbItem:4,\n\t                  }\n\t\t\t            },\t\t\t\t\t\t           \n\t\t\t        \t],\n\n                onSliderLoad: function(obj) {\n                jQuery('#gwts-gwl-img-gallery987976').removeClass('cS-hidden');\n\t                var lithbox = jQuery('#gwts-gwl-img-gallery987976').attr(\"data-litebx\");\n\t\t\t\t\t\t\t\t\tif(lithbox=='true'){\n\t\t\t\t\t\t\t\t\t\tobj.lightGallery({\n\t\t\t\t              selector: '#gwts-gwl-img-gallery987976 .lslide'\n\t\t\t\t            });\n\t\t\t\t\t\t\t\t\t}            \n                } \n              });\n            count++;\n          });\n\t      <\/script>\n\t\t\t\t\n\t\n\t\t \t<div class=\"item\">            \n\t      <div class=\"clearfix\" >\n\n\t        <ul id=\"gwts-gwl-img-gallery988770\" class=\"gwts-gwl-slidergal list-unstyled cS-hidden\" data-litebx=\"false\">\n\t\t\t\t    \n\t\t\t\t\t \t\t<li data-thumb=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/IMG_20160708_132405007-1030x579-1-150x150.jpeg\" data-responsive=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/IMG_20160708_132405007-1030x579-1-150x150.jpeg\" data-src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/IMG_20160708_132405007-1030x579-1.jpeg\" class=\"\"> \n              \t<img decoding=\"async\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/IMG_20160708_132405007-1030x579-1.jpeg\" alt=\"\"\/>\n              \t\t              <\/li>\n\t\t\t\t\t \t\n\t\t\t\t\t \t\t<li data-thumb=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/IMG_20160707_135455427-579x1030-1-150x150.jpeg\" data-responsive=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/IMG_20160707_135455427-579x1030-1-150x150.jpeg\" data-src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/IMG_20160707_135455427-579x1030-1.jpeg\" class=\"\"> \n              \t<img decoding=\"async\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/IMG_20160707_135455427-579x1030-1.jpeg\" alt=\"\"\/>\n              \t\t              <\/li>\n\t\t\t\t\t \t\n\t\t\t\t\t \t\t<li data-thumb=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/estufa-tipo-carro-1030x746-1-150x150.jpeg\" data-responsive=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/estufa-tipo-carro-1030x746-1-150x150.jpeg\" data-src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/estufa-tipo-carro-1030x746-1.jpeg\" class=\"\"> \n              \t<img decoding=\"async\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/estufa-tipo-carro-1030x746-1.jpeg\" alt=\"\"\/>\n              \t\t              <\/li>\n\t\t\t\t\t \t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<style type=\"text\/css\">\n\t\t\t\t.lSSlideOuter .lSSlideWrapper ul li img{\n\t\t\t\t  width: 100%;\n\t\t\t\t}\n\t\t\t<\/style>\n\n\t\t\t\t\t\t\t<style>\n\t\t\t\t\t.lSSlideOuter .lSPager.lSGallery {\n\t\t\t\t\t\tmargin-left: auto;\n\t\t\t\t\t\tmargin-right: auto;\n\t\t\t\t\t}\n\t\t\t\t<\/style>\n\t\t\t\t\t\t\t\t<script>\n\t\t    \tjQuery(document).ready(function() {\n\t\t        jQuery('#gwts-gwl-img-gallery988770').lightSlider({\n              item:1,\t\t                \n              slideMargin:10,\n              addClass:'',\n              speed:500,\n              pause:2000,\n              auto:false,\n              loop:false,\n              pager:true,\n              gallery:true,\n              thumbItem:9,\n\t    \t\t\t\tcontrols:true,\n\t    \t\t\t\t\t    \t\t\t\tresponsive : [\n\t\t            {\n\t                breakpoint:800,\n\t                settings: {\n                    item:1,\n                    slideMove:1,\n                  }\n\t\t            },\n\t\t            {\n\t                breakpoint:641,\n\t                settings: {\n                    item:1,\n                    slideMove:1,\n                  }\n\t\t            },\n\t\t            {\n\t                breakpoint:480,\n\t                settings: {\n                    item:1,\n                    slideMove:1,\n                  }\n\t\t            },\t\t\t\t\t\t           \n\t\t\t\t\t\t  ],\n\t    \t\t\t\t\tuseCSS: true,\n\t        \t\t\tcssEasing: 'ease',\n\t        \t\t\teasing: 'linear',\n\t        \t\t\tkeyPress: false,\n\t        \t\t\tslideEndAnimation: true,\n\t        \t\t\tswipeThreshold: 40,        \t\t\t\n\t\t              onSliderLoad: function(el) {\n                    jQuery('#gwts-gwl-img-gallery988770').removeClass('cS-hidden');\n                    jQuery('#gwts-gwl-img-gallery988770').addClass('gwts-loaded');\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\tvar lithbox = jQuery('#gwts-gwl-img-gallery988770').attr(\"data-litebx\");\n\t\t\t\t\t\t\t\t\t\tif(lithbox=='true'){\n\t\t\t\t\t\t\t\t\t\t\tel.lightGallery({\n\t\t\t\t\t               selector: '#gwts-gwl-img-gallery988770 .lslide'\n\t\t\t\t\t            });\n\t\t\t\t\t\t\t\t\t\t}\t\n\t\t              }  \n\t\t\t        });\n\t\t\t\t\t});\n\t\t    \t\t\t\t<\/script>\n\t\t \n\t<p>Equipamento voltado para processos unit\u00e1rios ou batelada. Desenvolvida para alta flexibilidade de processos de aquecimento e grande exatid\u00e3o em resultados de estabilidade de temperatura.<\/p>\n<p><b>Caracter\u00edsticas de constru\u00e7\u00e3o:<\/b><\/p>\n<ul>\n<li>Constru\u00edda em geometria consagrada pela efici\u00eancia, com aplica\u00e7\u00e3o de design intuitivo nas \u00e1reas de conectividade e intera\u00e7\u00e3o;<\/li>\n<li>Isolamentos t\u00e9rmicos projetados respeitando os par\u00e2metros de perfil t\u00e9rmico de face fria ergon\u00f4mica, visando economia de energia, efic\u00e1cia de aquecimento e conforto operacional;<\/li>\n<li>Carca\u00e7a e estrutura constru\u00eddas em materiais apropriados para a severidade da aplica\u00e7\u00e3o, garantindo robustez e longevidade ao equipamento;<\/li>\n<li>Sistemas de aquecimento desenvolvidos conforme o processo, sejam em elementos resistivos de alta efici\u00eancia, queimadores monoblocos, dual ou recuperativos;<\/li>\n<li>Efici\u00eancia energ\u00e9tica garantida por marcas mundialmente consagradas;<\/li>\n<li>Em aquecimentos el\u00e9tricos, conta com controle de pot\u00eancia por meios eletr\u00f4nicos de alta confiabilidade, via estado s\u00f3lido ou m\u00f3dulos tiristorizados;<\/li>\n<li>Em aquecimentos a g\u00e1s, os sistemas de controle t\u00eam programadores homologados e sistemas de seguran\u00e7a conforme NBR 12313;<\/li>\n<li>Sistema de controle de temperatura microprocessado, com rampas e patamares, pirometria de trabalho e seguran\u00e7a, avalia\u00e7\u00e3o e certifica\u00e7\u00e3o de v\u00e1rios pontos TUS;<\/li>\n<li>Contempla as Normas Brasileiras de Sa\u00fade e Seguran\u00e7a do Trabalho com: NR 10, NR 12, NR 17, relat\u00f3rio de An\u00e1lise Preliminar de Riscos, laudos de certifica\u00e7\u00e3o e ART de efetiva\u00e7\u00e3o.<\/li>\n<\/ul>\n<h2>\n\tBenef\u00edcios da Manuten\u00e7\u00e3o <br \/><strong>Grefortec<\/strong>\n\t<\/h2>\n\t<p>Contamos com uma equipe qualificada para atender manuten\u00e7\u00f5es corretivas e preventivas em equipamento industriais da nossa marca e tamb\u00e9m de outros fabricantes. Nossos profissionais s\u00e3o treinados e habilitados de acordo com as Normas de Seguran\u00e7a. Vamos at\u00e9 sua empresa para realizar a manuten\u00e7\u00e3o in loco.<\/p>\n\t\t\t\t\t\t\t65%\t\t\t\t\n\t\t\t<style>\n\t\t\t\t.fl-node- .fl-number-bars-container {\n\t\t\t\t\tbackground-color: var( --vamtam-accent-color-7 );\n\t\t\t\t}\n\t\t\t\t.fl-node- .fl-number-bar {\n\t\t\t\t\tbackground-color: var( --vamtam-accent-color-1 );\n\t\t\t\t}\n\t\t\t<\/style>\n\t<p>Do tempo de produ\u00e7\u00e3o \u00e9 desperdi\u00e7ado pela falta de manuten\u00e7\u00e3o <\/p>\n\t\t\t\t\t\t\t88%\t\t\t\t\n\t\t\t<style>\n\t\t\t\t.fl-node- .fl-number-bars-container {\n\t\t\t\t\tbackground-color: var( --vamtam-accent-color-7 );\n\t\t\t\t}\n\t\t\t\t.fl-node- .fl-number-bar {\n\t\t\t\t\tbackground-color: var( --vamtam-accent-color-1 );\n\t\t\t\t}\n\t\t\t<\/style>\n\t<p>Das empresas industriais utilizam a manuten\u00e7\u00e3o preventiva<\/p>\n\t\t\t\t\t\t\t97%\t\t\t\t\n\t\t\t<style>\n\t\t\t\t.fl-node- .fl-number-bars-container {\n\t\t\t\t\tbackground-color: var( --vamtam-accent-color-7 );\n\t\t\t\t}\n\t\t\t\t.fl-node- .fl-number-bar {\n\t\t\t\t\tbackground-color: var( --vamtam-accent-color-1 );\n\t\t\t\t}\n\t\t\t<\/style>\n\t<p>\u00c9 o \u00edndice de satisfa\u00e7\u00e3o com a manuten\u00e7\u00e3o Grefortec<\/p>\n<h3>\n\tReformas e Retrofit\n\t<\/h3>\n\t<p>Equipe especializada em reformas gerais, recuperando desde a estrutura e chaparia at\u00e9 as partes eletroeletr\u00f4nicas. A Grefortec tamb\u00e9m possui Know-Wow para servi\u00e7os de retrofit, reformas refrat\u00e1rias e de isola\u00e7\u00e3o.<\/p>\n<h3>\n\tDisponibilidade 24h\n\t<\/h3>\n\t<p>Nossa equipe t\u00e9cnica est\u00e1 dispon\u00edvel 24h por dia, com a possibilidade de realizar a manuten\u00e7\u00e3o in loco, sem necessidade de deslocamento. N\u00f3s vamos at\u00e9 a sua empresa!<\/p>\n\t<h2><strong>Pe\u00e7as de Reposi\u00e7\u00e3o<\/strong><\/h2>\n<p>Resist\u00eancias, tubos radiantes, correntes transportadoras, recirculadores de atmosfera, cestos, grelhas e itens diversos:<\/p>\n\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/resistencias-630x420.jpeg\" alt=\"Resist\u00eancia\" itemprop=\"image\" height=\"420\" width=\"630\" title=\"resistencias\" onerror=\"this.style.display='none'\"  sizes=\"auto, (max-width: 768px) 100vw, 100vw\" srcset=\"data:image\/svg+xml;utf8,&lt;svg%20xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;%20viewBox=&quot;0%200%20900%20600&quot;%20height=&quot;600px&quot;%20width=&quot;900px&quot;\/&gt;\" data-srcset=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/resistencias-630x420.jpeg 630w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/resistencias-300x200.jpeg 300w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/resistencias-768x512.jpeg 768w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/resistencias-420x280.jpeg 420w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/resistencias-840x560.jpeg 840w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/resistencias-315x210.jpeg 315w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/resistencias.jpeg 900w\" \/>\t\t\t\t\t\t\t\n\t<h4>Resist\u00eancia<\/h4>\n\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/tubos-radiantes-630x420.jpeg\" alt=\"tubos-radiantes\" itemprop=\"image\" height=\"420\" width=\"630\" title=\"tubos-radiantes\" onerror=\"this.style.display='none'\"  sizes=\"auto, (max-width: 768px) 100vw, 100vw\" srcset=\"data:image\/svg+xml;utf8,&lt;svg%20xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;%20viewBox=&quot;0%200%20900%20600&quot;%20height=&quot;600px&quot;%20width=&quot;900px&quot;\/&gt;\" data-srcset=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/tubos-radiantes-630x420.jpeg 630w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/tubos-radiantes-300x200.jpeg 300w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/tubos-radiantes-768x512.jpeg 768w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/tubos-radiantes-420x280.jpeg 420w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/tubos-radiantes-840x560.jpeg 840w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/tubos-radiantes-315x210.jpeg 315w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/tubos-radiantes.jpeg 900w\" \/>\t\t\t\t\t\t\t\n\t<h4>Tubos Radiadores<\/h4>\n\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/correntes-transportadoras-630x420.jpeg\" alt=\"correntes-transportadoras\" itemprop=\"image\" height=\"420\" width=\"630\" title=\"correntes-transportadoras\" onerror=\"this.style.display='none'\"  sizes=\"auto, (max-width: 768px) 100vw, 100vw\" srcset=\"data:image\/svg+xml;utf8,&lt;svg%20xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;%20viewBox=&quot;0%200%20900%20600&quot;%20height=&quot;600px&quot;%20width=&quot;900px&quot;\/&gt;\" data-srcset=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/correntes-transportadoras-630x420.jpeg 630w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/correntes-transportadoras-300x200.jpeg 300w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/correntes-transportadoras-768x512.jpeg 768w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/correntes-transportadoras-420x280.jpeg 420w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/correntes-transportadoras-840x560.jpeg 840w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/correntes-transportadoras-315x210.jpeg 315w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/correntes-transportadoras.jpeg 900w\" \/>\t\t\t\t\t\t\t\n\t<h4>Correntes Transportadoras<\/h4>\n\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/recirculadores.jpeg\" alt=\"recirculadores\" itemprop=\"image\" height=\"600\" width=\"900\" title=\"recirculadores\" onerror=\"this.style.display='none'\"  sizes=\"auto, (max-width: 768px) 100vw, 100vw\" srcset=\"data:image\/svg+xml;utf8,&lt;svg%20xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;%20viewBox=&quot;0%200%20900%20600&quot;%20height=&quot;600px&quot;%20width=&quot;900px&quot;\/&gt;\" data-srcset=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/recirculadores.jpeg 900w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/recirculadores-300x200.jpeg 300w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/recirculadores-768x512.jpeg 768w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/recirculadores-630x420.jpeg 630w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/recirculadores-420x280.jpeg 420w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/recirculadores-840x560.jpeg 840w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/recirculadores-315x210.jpeg 315w\" \/>\t\t\t\t\t\t\t\n\t<h4>Circuladores de Atmosfera<\/h4>\n\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/cestos-grelhas-300x200-1.jpeg\" alt=\"cestos-grelhas-300x200\" itemprop=\"image\" height=\"200\" width=\"300\" title=\"cestos-grelhas-300x200\" onerror=\"this.style.display='none'\"  sizes=\"auto, (max-width: 768px) 100vw, 100vw\"\/>\t\t\t\t\t\t\t\n\t<h4>Cestos e Grelhas<\/h4>\n\t\t\t\t\t\t\t<img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/itens-diversos.jpeg\" alt=\"itens-diversos\" itemprop=\"image\" height=\"600\" width=\"900\" title=\"itens-diversos\" onerror=\"this.style.display='none'\"  sizes=\"auto, (max-width: 768px) 100vw, 100vw\" srcset=\"data:image\/svg+xml;utf8,&lt;svg%20xmlns=&quot;http:\/\/www.w3.org\/2000\/svg&quot;%20viewBox=&quot;0%200%20900%20600&quot;%20height=&quot;600px&quot;%20width=&quot;900px&quot;\/&gt;\" data-srcset=\"https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/itens-diversos.jpeg 900w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/itens-diversos-300x200.jpeg 300w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/itens-diversos-768x512.jpeg 768w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/itens-diversos-630x420.jpeg 630w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/itens-diversos-420x280.jpeg 420w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/itens-diversos-840x560.jpeg 840w, https:\/\/site2022.grefortec.com.br\/wp-content\/uploads\/2022\/10\/itens-diversos-315x210.jpeg 315w\" \/>\t\t\t\t\t\t\t\n\t<h4>Itens Diversos<\/h4>\n\t<h2><strong>Solicitar Or\u00e7amento<\/strong><\/h2>\n    Aviso: O JavaScript \u00e9 necess\u00e1rio para esse conte\u00fado.\n        <!-- TODO: Move to Template File. -->\n        \n<\/div><!-- .vgblk-rw-wrapper -->","protected":false},"excerpt":{"rendered":"<p>Estufas Estacion\u00e1rias Equipamento voltado para processos unit\u00e1rios ou batelada. Desenvolvida para alta flexibilidade de processos de aquecimento e grande exatid\u00e3o em resultados de estabilidade de temperatura. Caracter\u00edsticas de constru\u00e7\u00e3o: Constru\u00edda em geometria consagrada pela efici\u00eancia, com aplica\u00e7\u00e3o de design intuitivo nas \u00e1reas de conectividade e intera\u00e7\u00e3o; Isolamentos t\u00e9rmicos projetados respeitando os par\u00e2metros de perfil t\u00e9rmico&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":12696,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-987853","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/pages\/987853","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=987853"}],"version-history":[{"count":30,"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/pages\/987853\/revisions"}],"predecessor-version":[{"id":988785,"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/pages\/987853\/revisions\/988785"}],"up":[{"embeddable":true,"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/pages\/12696"}],"wp:attachment":[{"href":"https:\/\/site2022.grefortec.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=987853"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}